{"id":8863,"date":"2023-09-01T17:33:11","date_gmt":"2023-09-01T17:33:11","guid":{"rendered":"https:\/\/www.academiahistoriamilitar.cl\/academia\/?p=8863"},"modified":"2023-09-01T17:35:43","modified_gmt":"2023-09-01T17:35:43","slug":"una-mirada-de-ohiggins-al-dia-de-hoy-2","status":"publish","type":"post","link":"https:\/\/www.academiahistoriamilitar.cl\/academia\/una-mirada-de-ohiggins-al-dia-de-hoy-2\/","title":{"rendered":"Una mirada de O&#8217;Higgins al d\u00eda de hoy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Bernardo O\u00b4Higgins mirando el Chile que tanto ayud\u00f3 a construir, desde el m\u00e1s all\u00e1, mostrar\u00eda por un lado una gran admiraci\u00f3n por lo que el pa\u00eds ha alcanzado en sus m\u00e1s de doscientos a\u00f1os de vida independiente. Por otro lado, reaccionar\u00eda con mucha desaz\u00f3n y quiz\u00e1s amargura ante la presencia de signos de divisi\u00f3n profunda y de intolerancia propios quiz\u00e1s de los tiempos que vive el mundo.<\/p>\n<p>El Padre de la Patria fue un adelantado para su \u00e9poca y su formaci\u00f3n en Lima y en Londres, le permiti\u00f3 conocer el mundo permiti\u00e9ndole generar un pensamiento avanzado como lo demuestran los escritos que nos leg\u00f3.<\/p>\n<p>Gener\u00f3 entonces una clara visi\u00f3n geopol\u00edtica para Chile. Hoy entonces mirar\u00eda con admiraci\u00f3n como el pa\u00eds ha consolidado y ampliado parte de su territorio, admirar\u00eda el desarrollo de las zonas extremas y nuestra presencia en la Ant\u00e1rtica. Resentir\u00eda sin lugar a duda la cesi\u00f3n de la Patagonia, de la Puna de Atacama, de Laguna del Desierto y de algunas \u00e1reas mar\u00edtimas. Su balance ser\u00eda positivo al observar c\u00f3mo se ha ido conectando f\u00edsicamente el territorio y c\u00f3mo el pa\u00eds ha defendido sus derechos en las doscientas millas en el mar, que todav\u00eda esconden infinitas riquezas. <\/p>\n","protected":false},"author":1,"featured_media":8862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-8863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fragmentos-de-historia-militar"],"_links":{"self":[{"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/posts\/8863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/comments?post=8863"}],"version-history":[{"count":3,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/posts\/8863\/revisions"}],"predecessor-version":[{"id":8866,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/posts\/8863\/revisions\/8866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/media\/8862"}],"wp:attachment":[{"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/media?parent=8863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/categories?post=8863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academiahistoriamilitar.cl\/academia\/wp-json\/wp\/v2\/tags?post=8863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}